{"id":1117,"date":"2025-09-24T12:30:00","date_gmt":"2025-09-24T15:30:00","guid":{"rendered":"https:\/\/igrejapequena.com.br\/blog\/?p=1117"},"modified":"2025-09-14T14:58:15","modified_gmt":"2025-09-14T17:58:15","slug":"setembro-amarelo-prevencao-ao-suicidio-e-saude-mental","status":"publish","type":"post","link":"https:\/\/igrejapequena.com.br\/blog\/setembro-amarelo-prevencao-ao-suicidio-e-saude-mental\/","title":{"rendered":"Setembro Amarelo: Preven\u00e7\u00e3o ao Suic\u00eddio e Sa\u00fade Mental"},"content":{"rendered":"\n<p>O m\u00eas de setembro \u00e9 marcado pela campanha Setembro Amarelo. Ela \u00e9 dedicada \u00e0 preven\u00e7\u00e3o do suic\u00eddio e \u00e0 promo\u00e7\u00e3o da sa\u00fade mental. A campanha busca quebrar tabus, incentivar o di\u00e1logo e apoiar pessoas em sofrimento emocional com a\u00e7\u00f5es em todo o Brasil: palestras, rodas de conversa, mobiliza\u00e7\u00e3o em redes sociais, etc.<\/p>\n\n\n\n<p>O tema ganha destaque diante do aumento dos casos de depress\u00e3o e ansiedade, especialmente entre jovens e adultos, e da necessidade de redes de apoio e acolhimento nas comunidades.<\/p>\n\n\n\n<p>Assim como em tantas outras coisas, a comunidade eclesi\u00e1stica local, parece que se sente imune a tais situa\u00e7\u00f5es. Como se a fragilidade da sa\u00fade emocional fosse exclusividade do que n\u00e3o pertence \u00e0 comunidade. Como se procurar ajuda psicol\u00f3gica ou psiquiatra fosse um sinal de falta de f\u00e9.<\/p>\n\n\n\n<p>Na realidade, procurar ajuda \u00e9 de por si um ato de humildade. Procurar ajuda especifica para manter, melhorar ou recuperar a sa\u00fade mental, \u00e9 um ato de gratid\u00e3o a Deus por ter dado ao Homem a gra\u00e7a de poder desvendar transversal e longitudinalmente as entranhas do emaranhado mental que \u00e9 a exist\u00eancia.<\/p>\n\n\n\n<p>Doen\u00e7as mentais, automutila\u00e7\u00e3o e suic\u00eddio, fazem parte da fragilidade e da dor da exist\u00eancia humana. Muitos s\u00e3o os que se insensibilizam perante a pr\u00f3pria dor com escapes de todo tipo, chame-se festas, drogas ou cultos religiosos. Necessariamente &#8220;ser humano&#8221; \u00e9 estar exposto ao sofrimento.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe class=\"youtube-player\" width=\"604\" height=\"340\" src=\"https:\/\/www.youtube.com\/embed\/RGWQMiSXdik?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=pt-BR&#038;autohide=2&#038;wmode=transparent&#038;listType=playlist&#038;list=PLZdOHN20BMRQh6ITkUR0uQCZriDQbrakh\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Sufici\u00eancia e necessidade<\/h2>\n\n\n\n<p>A grande armadilha de certas formas de f\u00e9 crist\u00e3 (promovidas a partir de pessoas que talvez n\u00e3o tenham parado para pensar no pr\u00f3ximo nem nas ferramentas que o outro possui ou n\u00e3o) \u00e9 de que &#8220;Cristo \u00e9 suficiente at\u00e9 para a sa\u00fade mental&#8221;.<\/p>\n\n\n\n<p>Se bem isso soa bonito e \u00e9 uma verdade soteriol\u00f3gica essencial, o certo \u00e9 que &#8211; assim como na santidade que n\u00e3o acontece por acaso e sim por dedica\u00e7\u00e3o do disc\u00edpulo &#8211; a B\u00edblia recomenda &#8220;Levem os fardos pesados um dos outros e, assim, cumpram a lei de Cristo&#8221; (G\u00e1l 6:2) e tamb\u00e9m &#8220;Confessem os seus pecados uns aos outros e orem uns pelos outros para que sejam curados&#8221; (Tiago 5:16) e tamb\u00e9m &#8220;N\u00e3o andem ansiosos por coisa alguma &#8230; com a\u00e7\u00e3o de gra\u00e7as, apresentem seus pedidos a Deus. E a paz de Deus &#8230; guardar\u00e1 o cora\u00e7\u00e3o e a mente de voc\u00eas em Cristo Jesus&#8221; (Fil 4:6-7)<\/p>\n\n\n\n<p>Agora, pense que voc\u00ea tem um acidente e quebra uma perna. Eu chego. O que devo fazer? Providenciar atendimento m\u00e9dico ou uma roda de ora\u00e7\u00e3o para que seu osso seja restaurado?<\/p>\n\n\n\n<p>A mente \u00e9 como um membro quebrado. Precisa de atendimento especializado e n\u00e3o quem toque de ouvido. O conselho b\u00edblico \u00e9 essencial neste ponto: &#8220;Confessem os seus pecados uns aos outros&#8221; Por que escolhi esse texto dos que elenquei logo acima? porque \u00e9 o mais sens\u00edvel de todos e vai ajudar a mostrar um ponto essencial aqui: Voc\u00ea, confessaria seus pecados para qualquer pessoa na sua congrega\u00e7\u00e3o? \u00d3bvio que n\u00e3o. Iria escolher algu\u00e9m que tivesse j\u00e1 algum tempo de ser bom disc\u00edpulo, algu\u00e9m que seja conhecido pela sua discri\u00e7\u00e3o e amorosidade no trato com os outros.<\/p>\n\n\n\n<p>Ningu\u00e9m deseja sofrer \u2014 exceto aqueles cuja sa\u00fade mental e identidade foram, desde a inf\u00e2ncia e por meio de diversos traumas, condicionadas a enxergar o sofrimento como algo normal e at\u00e9 desej\u00e1vel.<\/p>\n\n\n\n<p>Partindo desse ponto, podemos enxergar a vida do suicida (e todas suas variantes menores como a auto-mutila\u00e7\u00e3o) com maior compaix\u00e3o. A vida de ora\u00e7\u00e3o, a amizade da comunidade, as atividades recreativas, exerc\u00edcios e todo o mais \u00e9 necess\u00e1rio e ajuda. Mas nada substitui um bom ouvido, um abra\u00e7o e uma boa terapia.<\/p>\n\n\n\n<p>Finalmente, mas n\u00e3o menos importante, a ressurrei\u00e7\u00e3o de Jesus (que \u00e9 o &#8220;primog\u00eanito dentre os mortos&#8221;) nos traz esperan\u00e7a. N\u00e3o apenas para o futuro distante, mas para o presente concreto. Em outras palavras, a igreja tem um papel bem definido em ser espa\u00e7o de acolhimento e restaura\u00e7\u00e3o e n\u00e3o de condena e rejei\u00e7\u00e3o de certos indiv\u00edduos.<\/p>\n\n\n\n<p>Neste m\u00eas de setembro, que seu cuidado para com os que sofrem seja fortalecido pela liberdade que voc\u00ea tem em Cristo \u2014 para indicar um bom psic\u00f3logo, assim como recomendaria um traumatologista a algu\u00e9m ferido em um acidente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O artigo aborda a campanha Setembro Amarelo, destacando a import\u00e2ncia da sa\u00fade mental e da preven\u00e7\u00e3o ao suic\u00eddio. Critica a resist\u00eancia de algumas comunidades eclesi\u00e1sticas em reconhecer fragilidades emocionais, tratando o sofrimento como falta de f\u00e9. Prop\u00f5e uma abordagem crist\u00e3 mais sens\u00edvel, baseada na B\u00edblia, que incentiva o cuidado m\u00fatuo, a confiss\u00e3o e o apoio especializado. Afirma que procurar ajuda psicol\u00f3gica \u00e9 um ato de humildade e gratid\u00e3o a Deus. Defende que, assim como se recomenda um m\u00e9dico para uma fratura, deve-se recomendar psic\u00f3logos para dores emocionais. O cuidado espiritual e psicol\u00f3gico devem caminhar juntos.<\/p>\n","protected":false},"author":2,"featured_media":1119,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[55,150],"tags":[],"class_list":["post-1117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia","category-saude-mental"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/mlr63ku2e7ti.i.optimole.com\/w:auto\/h:auto\/q:mauto\/ig:avif\/https:\/\/igrejapequena.com.br\/blog\/wp-content\/uploads\/2025\/09\/ChatGPT-Image-Sep-6-2025-01_14_30-PM.png","jetpack_shortlink":"https:\/\/wp.me\/p4RFIP-i1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/igrejapequena.com.br\/blog\/wp-json\/wp\/v2\/posts\/1117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/igrejapequena.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/igrejapequena.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/igrejapequena.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/igrejapequena.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1117"}],"version-history":[{"count":6,"href":"https:\/\/igrejapequena.com.br\/blog\/wp-json\/wp\/v2\/posts\/1117\/revisions"}],"predecessor-version":[{"id":1141,"href":"https:\/\/igrejapequena.com.br\/blog\/wp-json\/wp\/v2\/posts\/1117\/revisions\/1141"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/igrejapequena.com.br\/blog\/wp-json\/wp\/v2\/media\/1119"}],"wp:attachment":[{"href":"https:\/\/igrejapequena.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/igrejapequena.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/igrejapequena.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}