{"id":746,"date":"2019-05-07T06:13:29","date_gmt":"2019-05-07T09:13:29","guid":{"rendered":"http:\/\/igrejapequena.com.br\/blog\/?p=746"},"modified":"2019-08-09T08:33:42","modified_gmt":"2019-08-09T11:33:42","slug":"a-heranca-esquecida-julio","status":"publish","type":"post","link":"https:\/\/igrejapequena.com.br\/blog\/a-heranca-esquecida-julio\/","title":{"rendered":"A heran\u00e7a esquecida &#8211; J\u00falio"},"content":{"rendered":"\n<p><a href=\"https:\/\/igrejapequena.com.br\/blog\/a-heranca-esquecida\/\">Anteriormente&#8230;<\/a><\/p>\n\n\n\n<p>J\u00falio n\u00e3o era de todo circular. Suas ideias iam e vinham. Algumas eram ideias estranhas. Bom, ao menos n\u00e3o eram circulares. Para falar a verdade, J\u00falio era mesmo meio amassado. Ele n\u00e3o girava muito bem. At\u00e9 o c\u00edrculo particular se incomodava com o jeito em que ele girava. No c\u00edrculo simulado ele n\u00e3o se encaixava e vira e mexe falava de coisas que s\u00f3 podiam ter vindo do c\u00edrculo externo irreal. Para que o leitor me entenda melhor, mais do que girar em c\u00edrculos, o J\u00falio rodopiava alternando a vol\u00fapia rodo ativa com certo <em>degringolamento<\/em> na pr\u00f3pria rota: Um louco solto.<\/p>\n\n\n\n<p>Uma das coisas mais perigosas que J\u00falio falava era que o \u00faltimo c\u00edrculo estava mal etiquetado. Ele dizia que o \u00faltimo c\u00edrculo n\u00e3o podia levar nunca a palavra <em>irreal<\/em> na etiqueta. Apenas <em>c\u00edrculo externo<\/em> seria suficiente. Apenas pensar nesta ideia fazia os circul\u00f5es (assim eram chamados os membros deste povo), como dizia, apenas pensar nesta ideia fazia os circul\u00f5es mais velhos estremecerem na base. Como o leitor pode imaginar, uma estremecida neste povo n\u00e3o era o mais desej\u00e1vel j\u00e1 que um c\u00edrculo poderia bater no outro, fazendo-o estremecer-se e podendo desencadear uma rea\u00e7\u00e3o em cadeia.<\/p>\n\n\n\n<p>Da \u00faltima vez que isso tinha acontecido o desmoronamento, o tombo, a sensa\u00e7\u00e3o de inseguran\u00e7a tinham invadido o povo ao ponto que \u2013 n\u00e3o podendo mais rejeitar as ideias \u2013 tiveram que se desfazer do circul\u00e3o ousado. Como era que se chamava? Era um nome com \u00e9sse. Sofos? Saliente? Solid\u00e3o? Salvador? \u00c9 isso ai! O circul\u00e3o aloprado chamava Salvador.<\/p>\n\n\n\n<p>Salvador tinha a mania de mostrar que c\u00edrculos, por mais enormes e velhos que fossem, nunca seriam linhas retas. Ele insistia que haviam outras formas igualmente v\u00e1lidas de construir um povo; tri\u00e2ngulos, quadrados, pent\u00e1gonos, etc. O problema estava com o caminho. Segundo Salvador, o essencial era reconhecer que o andar n\u00e3o podia estar limitado \u00e0 reprodu\u00e7\u00e3o da pr\u00f3pria forma do povo. Ou seja, ele dizia que haviam outros povos no <em>c\u00edrculo externo irreal<\/em> que alias, ele -que nem J\u00falio- insistia em tirar a palavra <em>irreal<\/em> da etiqueta. Estes povos tinham as formas mais variadas mas todas elas, assim como os circul\u00f5es, insistiam em que o caminho a ser seguido tinha a pr\u00f3pria forma do membro individual do povo apenas mudando em tamanho e \u2013 por consequ\u00eancia \u2013 em historicidade. Quando mais velho e maior, tanto melhor e seguro o caminho a ser seguido; isso contanto a forma fosse id\u00eantica \u00e0 do povo que o transitasse.<\/p>\n\n\n\n<p>Salvador insistia em que a forma que o caminho assumia e o tempo transitado n\u00e3o eram um atestado de que o pr\u00f3prio caminho era certo. Por outro lado, estas coisas n\u00e3o tinham como competir com a relev\u00e2ncia do destino a ser atingido nem muito menos com a aventura das descobertas que o pr\u00f3prio caminho poderia vir a oferecer.<\/p>\n\n\n\n<p>O orgulho com que os circul\u00f5es se gabavam de qu\u00e3o seguro era seu pr\u00f3prio caminho, qu\u00e3o elegante e suave era se comparado ao dos triangul\u00f5es ou dos quadrad\u00f5es via-se gravemente amea\u00e7ado pelo sorriso meigo e simples de Salvador que \u2013 na sua aparente loucura \u2013 conseguia enxergar vida al\u00e9m do <em>c\u00edrculo externo irreal<\/em>.<\/p>\n\n\n\n<p>As pessoas que o ouviam falar, o faziam por meio do <em>c\u00edrculo simulado<\/em>. Este era meio como que uma \u00faltima linha de defesa para a pseudo realidade particular e a quase realidade interior. No c\u00edrculo simulado, a realidade era antag\u00f4nica \u00e0 aceita\u00e7\u00e3o. As ideias eram expostas sempre e quando fossem circulares. Maiores, menores; com tra\u00e7os largos ou finos; mas circulares. Os mais ousados traziam ideias ovais que n\u00e3o passavam de c\u00edrculos deformados. Passado o choque inicial, a ideia passava a ser considerada pois n\u00e3o se tratava de nada mais do que um c\u00edrculo sob forte press\u00e3o ou qualquer eufemismo do tipo.<\/p>\n\n\n\n<p>Salvador vinha e falava de tri\u00e2ngulos, quadrados, hex\u00e1gonos e outros pol\u00edgonos como se eles tamb\u00e9m fossem formas v\u00e1lidas de vida. Mostrava aos circul\u00f5es que tanto fossem triangul\u00f5es, quadrad\u00f5es, ou circul\u00f5es, o importante mesmo era escolher um outro caminho que n\u00e3o era a mesmice de sempre. Por\u00e9m a coisa realmente pegava quando ele abandonava os pol\u00edgonos e passava a falar dos poliedros. Onde j\u00e1 se viu ter tr\u00eas dimens\u00f5es? Volume? \u00c9 claro que ele fazia isso n\u00e3o apenas para chacoalhar as ideias dentro do c\u00edrculo \u00edntimo de cada circul\u00e3o o que j\u00e1 de por si constituiria um objetivo bastante ousado. O prop\u00f3sito dele era mostrar que o importante era o caminho e n\u00e3o a forma de quem o transita.<\/p>\n\n\n\n<p>J\u00falio se sentia de certa forma conectado com Salvador. N\u00e3o que fossem contempor\u00e2neos. Nada disso. Havia uns dois mil anos de separa\u00e7\u00e3o hist\u00f3rica. A coisa era mais profunda.<br>J\u00falio tinha nascido como qualquer outro circul\u00e3o; ou seja: dois circul\u00f5es complementares se uniam, mitigando as diferen\u00e7as do c\u00edrculo simulado e passando a constituir um novo c\u00edrculo particular, abandonando \u2013 na medida do poss\u00edvel \u2013 os respectivos c\u00edrculos particulares ao que tinham pertencido para formar um outro circulo melhor e maior na medida do poss\u00edvel ou pelo menos aparentar que assim era.<\/p>\n\n\n\n<p>Bem, particularidades \u00e0 parte, J\u00falio foi crescendo bastante bem. Aprendeu as habilidades de simular o pensamento, esconder a verdade, fugir das ideias que n\u00e3o fossem circulares, enfim, tudo aquilo que os mais antigos achavam essencial para o pequeno J\u00falio chegar com sucesso a participar do <em>c\u00edrculo simulado<\/em> e evitar o mais poss\u00edvel o contato com o <em>c\u00edrculo externo irreal<\/em>. A n\u00e3o ser, claro, aquelas vezes em que a necessidade o empurrasse para obter algum recurso com os triangul\u00f5es ou os quadrad\u00f5es vizinhos.<\/p>\n\n\n\n<p>&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anteriormente&#8230; J\u00falio n\u00e3o era de todo circular. Suas ideias iam e vinham. Algumas eram ideias estranhas. Bom, ao menos n\u00e3o eram circulares. Para falar a verdade, J\u00falio era mesmo meio amassado. Ele n\u00e3o girava muito bem. At\u00e9 o c\u00edrculo particular se incomodava com o jeito em que ele girava. No c\u00edrculo simulado ele n\u00e3o se &hellip; <a href=\"https:\/\/igrejapequena.com.br\/blog\/a-heranca-esquecida-julio\/\" class=\"more-link\">Continue lendo <span class=\"screen-reader-text\">A heran\u00e7a esquecida &#8211; J\u00falio<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[88,14,4,53,11],"tags":[],"class_list":["post-746","post","type-post","status-publish","format-standard","hentry","category-heranca","category-conversao","category-essencia","category-religiao","category-sociedade"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p4RFIP-c2","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/igrejapequena.com.br\/blog\/wp-json\/wp\/v2\/posts\/746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/igrejapequena.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/igrejapequena.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/igrejapequena.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/igrejapequena.com.br\/blog\/wp-json\/wp\/v2\/comments?post=746"}],"version-history":[{"count":4,"href":"https:\/\/igrejapequena.com.br\/blog\/wp-json\/wp\/v2\/posts\/746\/revisions"}],"predecessor-version":[{"id":772,"href":"https:\/\/igrejapequena.com.br\/blog\/wp-json\/wp\/v2\/posts\/746\/revisions\/772"}],"wp:attachment":[{"href":"https:\/\/igrejapequena.com.br\/blog\/wp-json\/wp\/v2\/media?parent=746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/igrejapequena.com.br\/blog\/wp-json\/wp\/v2\/categories?post=746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/igrejapequena.com.br\/blog\/wp-json\/wp\/v2\/tags?post=746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}